{"id":2360,"date":"2020-04-10T09:14:18","date_gmt":"2020-04-10T07:14:18","guid":{"rendered":"http:\/\/parafiaklimkowka.pl\/?p=2360"},"modified":"2020-10-24T00:18:29","modified_gmt":"2020-10-23T22:18:29","slug":"wywies-flage","status":"publish","type":"post","link":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/","title":{"rendered":"Wywie\u015b flag\u0119"},"content":{"rendered":"<h4 style=\"text-align: center;\"><strong>Wywie\u015b flag\u0119 \u2013 \u015awi\u0119to Chrztu Polski<\/strong><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2362 size-full aligncenter\" src=\"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg\" alt=\"\" width=\"491\" height=\"350\" srcset=\"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg 491w, https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga-300x214.jpg 300w\" sizes=\"(max-width: 491px) 100vw, 491px\" \/><\/p>\n<p style=\"text-align: justify;\">Akcja Katolicka w Polsce wraz z Fundacj\u0105 \u201eS\u0142owo\u201d zaprasza do \u015awi\u0119towania Chrztu Polski. Zach\u0119camy Rodak\u00f3w do w\u0142\u0105czenia si\u0119 w dniu 14 kwietnia 2020 w akcj\u0119 \u201eWywie\u015b flag\u0119\u201d. Wywieszanie w tym dniu flagi pa\u0144stwowej, nie tylko podkre\u015bli wag\u0119 tego \u015awi\u0119ta w naszej Ojczy\u017anie, ale te\u017c w tym trudnym czasie pandemii koronawirusa, nie pozwoli zapomnie\u0107 o naszych chrze\u015bcija\u0144skich korzeniach. Jako \u015bwieccy Ko\u015bcio\u0142a staramy si\u0119 czuwa\u0107 i podejmowa\u0107 bezpieczne akcje. Podzielmy si\u0119 na stronach internetowych i niezliczonych kontach spo\u0142eczno\u015bciowych plakatem zach\u0119caj\u0105cym do uroczystego \u015bwi\u0119towania narodzin naszego Pa\u0144stwa.<\/p>\n<p style=\"text-align: justify;\">Rok temu, 9 kwietnia 2019 r. w Dzienniku Ustaw zosta\u0142a og\u0142oszona ustawa \u201e\u015awi\u0119to Chrztu Polski\u201d. Na mocy tej ustawy \u015bwi\u0119to to, jest \u015awi\u0119tem Pa\u0144stwowym obchodzonym w dniu 14 kwietnia. Na podstawie bada\u0144 historycznych, data ta jest uznana jako dzie\u0144 narodzin Pa\u0144stwa Polskiego z racji przyj\u0119cia przez Mieszka I chrztu. Jest to jedna z najwa\u017cniejszych dat w historii Polski, kt\u00f3ra rozpocz\u0119\u0142a chrystianizacj\u0119 naszej Ojczyzny i da\u0142a pocz\u0105tek naszej pa\u0144stwowo\u015bci.<\/p>\n<p style=\"text-align: justify;\">\u015awi\u0119to to obchodzimy w Polsce dopiero po raz drugi, i z tego wzgl\u0119du nie jest ono powszechnie przyj\u0119te przez spo\u0142ecze\u0144stwo polskie. Dlatego w imieniu Parafialnego Oddzia\u0142u Akcji Katolickiej zach\u0119camy Parafian do w\u0142\u0105czenia si\u0119 w dniu 14 kwietnia w Akcj\u0119.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>10 kwietnia 2020<\/p>\n","protected":false},"author":1,"featured_media":2362,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[19],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wywie\u015b flag\u0119 - Parafia w Klimk\u00f3wce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wywie\u015b flag\u0119 - Parafia w Klimk\u00f3wce\" \/>\n<meta property=\"og:description\" content=\"10 kwietnia 2020\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/\" \/>\n<meta property=\"og:site_name\" content=\"Parafia w Klimk\u00f3wce\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-10T07:14:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-23T22:18:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"491\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kadmins70\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"kadmins70\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/\"},\"author\":{\"name\":\"kadmins70\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/#\/schema\/person\/8411339f73ed143172a1fc20b8c20562\"},\"headline\":\"Wywie\u015b flag\u0119\",\"datePublished\":\"2020-04-10T07:14:18+00:00\",\"dateModified\":\"2020-10-23T22:18:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/#organization\"},\"image\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg\",\"articleSection\":[\"Wiadomo\u015bci\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/\",\"url\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/\",\"name\":\"Wywie\u015b flag\u0119 - Parafia w Klimk\u00f3wce\",\"isPartOf\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg\",\"datePublished\":\"2020-04-10T07:14:18+00:00\",\"dateModified\":\"2020-10-23T22:18:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#primaryimage\",\"url\":\"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg\",\"contentUrl\":\"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg\",\"width\":491,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/parafiaklimkowka.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wywie\u015b flag\u0119\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/#website\",\"url\":\"https:\/\/parafiaklimkowka.pl\/\",\"name\":\"Parafia w Klimk\u00f3wce\",\"description\":\"pw. \u015aw. Micha\u0142a Archanio\u0142a\",\"publisher\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/parafiaklimkowka.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/#organization\",\"name\":\"Parafia p.w. \u015bw. Micha\u0142a Archanio\u0142a w Klimk\u00f3wce\",\"url\":\"https:\/\/parafiaklimkowka.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2019\/10\/anio\u01428_jpeg.jpg\",\"contentUrl\":\"http:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2019\/10\/anio\u01428_jpeg.jpg\",\"width\":658,\"height\":483,\"caption\":\"Parafia p.w. \u015bw. Micha\u0142a Archanio\u0142a w Klimk\u00f3wce\"},\"image\":{\"@id\":\"https:\/\/parafiaklimkowka.pl\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/#\/schema\/person\/8411339f73ed143172a1fc20b8c20562\",\"name\":\"kadmins70\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/parafiaklimkowka.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2f1a9b134b0f743459e06c66845f8cf1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2f1a9b134b0f743459e06c66845f8cf1?s=96&d=mm&r=g\",\"caption\":\"kadmins70\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wywie\u015b flag\u0119 - Parafia w Klimk\u00f3wce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/","og_locale":"pl_PL","og_type":"article","og_title":"Wywie\u015b flag\u0119 - Parafia w Klimk\u00f3wce","og_description":"10 kwietnia 2020","og_url":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/","og_site_name":"Parafia w Klimk\u00f3wce","article_published_time":"2020-04-10T07:14:18+00:00","article_modified_time":"2020-10-23T22:18:29+00:00","og_image":[{"width":491,"height":350,"url":"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg","type":"image\/jpeg"}],"author":"kadmins70","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"kadmins70","Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#article","isPartOf":{"@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/"},"author":{"name":"kadmins70","@id":"https:\/\/parafiaklimkowka.pl\/#\/schema\/person\/8411339f73ed143172a1fc20b8c20562"},"headline":"Wywie\u015b flag\u0119","datePublished":"2020-04-10T07:14:18+00:00","dateModified":"2020-10-23T22:18:29+00:00","mainEntityOfPage":{"@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/"},"wordCount":235,"publisher":{"@id":"https:\/\/parafiaklimkowka.pl\/#organization"},"image":{"@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#primaryimage"},"thumbnailUrl":"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg","articleSection":["Wiadomo\u015bci"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/","url":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/","name":"Wywie\u015b flag\u0119 - Parafia w Klimk\u00f3wce","isPartOf":{"@id":"https:\/\/parafiaklimkowka.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#primaryimage"},"image":{"@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#primaryimage"},"thumbnailUrl":"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg","datePublished":"2020-04-10T07:14:18+00:00","dateModified":"2020-10-23T22:18:29+00:00","breadcrumb":{"@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#primaryimage","url":"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg","contentUrl":"https:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2020\/04\/flaga.jpg","width":491,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/parafiaklimkowka.pl\/index.php\/2020\/04\/10\/wywies-flage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/parafiaklimkowka.pl\/"},{"@type":"ListItem","position":2,"name":"Wywie\u015b flag\u0119"}]},{"@type":"WebSite","@id":"https:\/\/parafiaklimkowka.pl\/#website","url":"https:\/\/parafiaklimkowka.pl\/","name":"Parafia w Klimk\u00f3wce","description":"pw. \u015aw. Micha\u0142a Archanio\u0142a","publisher":{"@id":"https:\/\/parafiaklimkowka.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parafiaklimkowka.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/parafiaklimkowka.pl\/#organization","name":"Parafia p.w. \u015bw. Micha\u0142a Archanio\u0142a w Klimk\u00f3wce","url":"https:\/\/parafiaklimkowka.pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/parafiaklimkowka.pl\/#\/schema\/logo\/image\/","url":"http:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2019\/10\/anio\u01428_jpeg.jpg","contentUrl":"http:\/\/parafiaklimkowka.pl\/wp-content\/uploads\/2019\/10\/anio\u01428_jpeg.jpg","width":658,"height":483,"caption":"Parafia p.w. \u015bw. Micha\u0142a Archanio\u0142a w Klimk\u00f3wce"},"image":{"@id":"https:\/\/parafiaklimkowka.pl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/parafiaklimkowka.pl\/#\/schema\/person\/8411339f73ed143172a1fc20b8c20562","name":"kadmins70","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/parafiaklimkowka.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f1a9b134b0f743459e06c66845f8cf1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f1a9b134b0f743459e06c66845f8cf1?s=96&d=mm&r=g","caption":"kadmins70"}}]}},"_links":{"self":[{"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/posts\/2360"}],"collection":[{"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/comments?post=2360"}],"version-history":[{"count":4,"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/posts\/2360\/revisions"}],"predecessor-version":[{"id":2365,"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/posts\/2360\/revisions\/2365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/media\/2362"}],"wp:attachment":[{"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/media?parent=2360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/categories?post=2360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/parafiaklimkowka.pl\/index.php\/wp-json\/wp\/v2\/tags?post=2360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}